{"id":101334,"date":"2023-06-08T19:00:15","date_gmt":"2023-06-08T17:00:15","guid":{"rendered":"https:\/\/www.sp-ps.ch\/?post_type=cpt-campaign&#038;p=101334"},"modified":"2026-05-06T09:21:13","modified_gmt":"2026-05-06T07:21:13","slug":"initiative-democratie","status":"publish","type":"cpt-campaign","link":"https:\/\/www.sp-ps.ch\/fr\/campagne\/initiative-democratie\/","title":{"rendered":"Initiative \u00ab\u00a0Pour un droit de la nationalit\u00e9 moderne\u00a0\u00bb"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"101334\" class=\"elementor elementor-101334 elementor-101333\" data-elementor-post-type=\"cpt-campaign\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0007e94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0007e94\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c564fd7\" data-id=\"c564fd7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80e9bc7 elementor-widget__width-inherit elementor-widget elementor-widget-elementor_spps_campaignheader_widget\" data-id=\"80e9bc7\" data-element_type=\"widget\" data-widget_type=\"elementor_spps_campaignheader_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<header class=\"petitionHeader\">  <div class=\"petitionHeader__content\">      <h1 class=\"petitionHeader__title\">      <\/h1>  <img decoding=\"async\"  alt=\"Hintergrundbild \"        src=\"https:\/\/www.sp-ps.ch\/wp-content\/uploads\/2023\/06\/Group-674.png\"        sizes=\"100vw\"        class=\"petitionHeader__img\">    <div class=\"petitionHeader__introWrapper\">      <h2 class=\"petitionHeader__intro\">Initiative \u00ab Pour un droit de la nationalit\u00e9 moderne \u00bb <\/h2>    <\/div>  <\/div><\/header>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a6cdf1 elementor-widget__width-initial elementor-widget elementor-widget-spps_button_list\" data-id=\"4a6cdf1\" data-element_type=\"widget\" data-widget_type=\"spps_button_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-list-wrapper   \"><div class=\"button-list-container\"><div class=\"button-list-text\"><h3>Il est temps d\u2019augmenter la d\u00e9mocratie !\u00a0<\/h3><p>Plus d\u2019un quart de la population r\u00e9sidant en Suisse ne dispose pas du passeport suisse, bien que de nombreuses personnes concern\u00e9es soient n\u00e9es et aient grandi en Suisse. L\u2019initiative pour la d\u00e9mocratie veut changer cela : quiconque vit en Suisse doit pouvoir faire valoir un droit \u00e0 la naturalisation. Pour cela, des crit\u00e8res objectifs de naturalisation doivent \u00eatre d\u00e9finis. Les proc\u00e9dures arbitraires et vexatoires doivent appartenir au pass\u00e9.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eefb91d elementor-widget elementor-widget-spacer\" data-id=\"eefb91d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb76527 elementor-widget__width-initial elementor-widget elementor-widget-spps_button_list\" data-id=\"cb76527\" data-element_type=\"widget\" data-widget_type=\"spps_button_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-list-wrapper   \"><div class=\"button-list-title\"><h3>Ce que demande l\u2019initiative :<\/h3><\/div><div class=\"button-list-container\"><div class=\"button-list-text\"><h4>Un passeport suisse pour toutes celles et tous ceux qui vivent ici<\/h4><p>La Suisse dispose de l\u2019un des droits de naturalisation les plus restrictifs d\u2019Europe. De ce fait, plus de deux millions de personnes paient des imp\u00f4ts, travaillent et vivent ici depuis des d\u00e9cennies, mais n\u2019ont pas leur mot \u00e0 dire dans le d\u00e9bat public. Il est temps de reconna\u00eetre ces personnes comme des membres \u00e0 part enti\u00e8re de notre soci\u00e9t\u00e9.<\/p><h4><br \/>Pour des crit\u00e8res justes contre les d\u00e9cisions arbitraires<\/h4><p>Les grandes diff\u00e9rences entre les r\u00e9glementations cantonales en mati\u00e8re de naturalisation et leur mise en \u0153uvre conduisent \u00e0 des in\u00e9galit\u00e9s de droit et \u00e0 des d\u00e9cisions arbitraires. La naturalisation doit enfin se faire sur la base de conditions objectivement mesurables : doit avoir droit \u00e0 la naturalisation toute personne qui vit l\u00e9galement en Suisse depuis cinq ans, qui dispose de connaissances de base d\u2019une langue nationale et qui n\u2019a pas \u00e9t\u00e9 condamn\u00e9e \u00e0 une peine privative de libert\u00e9 de longue dur\u00e9e ni ne menace la s\u00e9curit\u00e9 int\u00e9rieure ou ext\u00e9rieure de la Suisse.<\/p><h4><br \/>Pour une v\u00e9ritable d\u00e9mocratie<\/h4><p>Le principe d\u00e9mocratique exige que les d\u00e9bats politiques soient men\u00e9s sur un pied d\u2019\u00e9galit\u00e9. Un tel principe est viol\u00e9 tant que les trois quarts de la population peuvent d\u00e9cider du quart restant. La d\u00e9mocratie exige que toutes les personnes concern\u00e9es disposent des m\u00eames droits politiques. C\u2019est ce que nous voulons obtenir avec cette initiative.<\/p><h4><br \/>Garantir les droits fondamentaux<\/h4><p>La citoyennet\u00e9 ne se limite pas au droit de vote et d\u2019\u00e9ligibilit\u00e9. Elle garantit la s\u00e9curit\u00e9 du s\u00e9jour, prot\u00e8ge contre une expulsion et permet de voyager et de se d\u00e9placer librement \u2013 ind\u00e9pendamment de son statut de s\u00e9jour. La citoyennet\u00e9 permet une v\u00e9ritable participation et seule la citoyennet\u00e9 garantit les droits fondamentaux et les droits humains.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-532ffcc elementor-widget elementor-widget-spacer\" data-id=\"532ffcc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de2ae2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de2ae2d\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6efb789\" data-id=\"6efb789\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fd7efa elementor-widget elementor-widget-spacer\" data-id=\"4fd7efa\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1201b5e elementor-widget elementor-widget-accordion\" data-id=\"1201b5e\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1881\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1881\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Plus sur l\u2019initiative<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1881\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1881\"><p>Plus d\u2019informations sur l\u2019initiative dans nos publications<\/p><ul><li><a href=\"https:\/\/www.sp-ps.ch\/fr\/artikel-kanal\/magazine-solidaires\/\">Solidaires<\/a><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1882\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1882\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Le texte de l'initiative<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1882\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1882\"><p>Initiative populaire f\u00e9d\u00e9rale \u00ab Pour un droit de la nationalit\u00e9 moderne (initiative pour la d\u00e9mocratie) \u00bb<\/p><p>La Constitution1est modifi\u00e9e comme suit:<br \/>Art. 38, al. 2<\/p><p>2 Elle [la Conf\u00e9d\u00e9ration] l\u00e9gif\u00e8re sur la naturalisation des \u00e9trangers.<\/p><p>A droit \u00e0 l\u2019octroi de la nationalit\u00e9 suisse sur demande tout \u00e9tranger:<\/p><ul><li>qui s\u00e9journe l\u00e9galement en Suisse depuis cinq ans;<\/li><li>qui n\u2019a pas \u00e9t\u00e9 condamn\u00e9 \u00e0 une peine privative de libert\u00e9 de longue dur\u00e9e;<\/li><li>qui ne met pas en danger la s\u00fbret\u00e9 int\u00e9rieure ou ext\u00e9rieure de la Suisse, et<\/li><li>qui poss\u00e8de des connaissances de base dans une langue nationale.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"template":"elementor_canvas","meta":{"open_link_in_new_window":"false"},"categories":[],"class_list":["post-101334","cpt-campaign","type-cpt-campaign","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-campaign\/101334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-campaign"}],"about":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/types\/cpt-campaign"}],"version-history":[{"count":31,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-campaign\/101334\/revisions"}],"predecessor-version":[{"id":183253,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-campaign\/101334\/revisions\/183253"}],"wp:attachment":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/media?parent=101334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/categories?post=101334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}