{"id":56913,"date":"2013-10-08T00:00:00","date_gmt":"2013-10-07T22:00:00","guid":{"rendered":"https:\/\/test.sp-ps.ch\/artikel\/referendum-le-gripen-a-officiellement-du-plomb-dans-laile\/"},"modified":"2022-08-14T09:50:40","modified_gmt":"2022-08-14T07:50:40","slug":"referendum-le-gripen-a-officiellement-du-plomb-dans-laile","status":"publish","type":"post","link":"https:\/\/www.sp-ps.ch\/fr\/artikel\/referendum-le-gripen-a-officiellement-du-plomb-dans-laile\/","title":{"rendered":"Referendum : le Gripen a officiellement du plomb dans l\u2019aile"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"56913\" class=\"elementor elementor-56913 elementor-55321\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62f3cae074da6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62f3cae074da6\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62f3cae074da9\" data-id=\"62f3cae074da9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f3cae0693f4 elementor-widget elementor-widget-text-editor\" data-id=\"62f3cae0693f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUne large alliance des partis de gauche et de diverses associations rejette le Gripen, avion fant\u00f4me, bien trop cher et parfaitement inutile. Plus de trois milliards de francs pour l\u2019achat de nouveaux avions de combat repr\u00e9sentent une h\u00e9r\u00e9sie financi\u00e8re sur le dos des contribuables. Alors que l\u2019avion choisi par le Conseil f\u00e9d\u00e9ral n\u2019existe encore que sur le papier, l\u2019achat de ce nouvel avion de combat est totalement superflu du point de vue s\u00e9curitaire, la Suisse ayant d\u00e9pens\u00e9 r\u00e9cemment une centaine de millions de francs afin de moderniser les F\/A-18 existants.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3cae069486 elementor-widget elementor-widget-text-editor\" data-id=\"62f3cae069486\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;alliance contre l&rsquo;achat de nouveaux avions de combat a tenu ce jour une conf&eacute;rence de presse, afin de lancer officiellement le referendum. Au vu des nombreux retours qui parviennent, depuis la d&eacute;cision du Parlement, aux divers partis et associations engag&eacute;s, l&rsquo;alliance est particuli&egrave;rement confiante sur le fait de rassembler l&rsquo;entier des signataires n&eacute;cessaires cette ann&eacute;e encore.<p>La population aura donc le dernier mot au cours de l&rsquo;ann&eacute;e prochaine. Elle pourra ainsi d&eacute;terminer si plus de 3 milliards de francs pour de nouveaux avions peuvent &ecirc;tre consid&eacute;r&eacute;s comme un investissement raisonnable. Par ailleurs, en comptant l&rsquo;entier des co&ucirc;ts, notamment d&rsquo;exploitation et d&rsquo;entretien, la facture finale r&eacute;elle sera plus proche des 9 milliards.<\/p><p>Un tel gaspillage d&rsquo;argent public est particuli&egrave;rement inqui&eacute;tant, alors que le Conseil f&eacute;d&eacute;ral lui-m&ecirc;me rappelait dans son rapport sur la politique de s&eacute;curit&eacute; 2010, que l&rsquo;achat de nouveaux avions de combat &eacute;tait consid&eacute;r&eacute; comme non-n&eacute;cessaire. La Suisse poss&egrave;de d&eacute;j&agrave; une flotte largement suffisante de F\/A-18, afin de mener &agrave; bien les missions de police a&eacute;rienne. Enfin, le mod&egrave;le retenu par la Conf&eacute;d&eacute;ration n&rsquo;existe aujourd&rsquo;hui que sur le papier. La d&eacute;b&acirc;cle des mirages dans les ann&eacute;es 1960 ne devrait pas &ecirc;tre oubli&eacute;e aussi vite et devrait servir d&rsquo;avertissement aux d&eacute;fenseurs d&rsquo;un avion fant&ocirc;me.&nbsp;<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3cae074122 elementor-widget elementor-widget-spps_button_list\" data-id=\"62f3cae074122\" data-element_type=\"widget\" data-widget_type=\"spps_button_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-list-wrapper wrapper-spacing-small  \"><div class=\"button-list-title\"><h3>Mat\u00e9riel<\/h3><\/div><div class=\"button-list-container\"><div class=\"button-list-items\"><div class=\"button-list-item\"><div class=\"button-wrapper \"><a href=\"https:\/\/www.sp-ps.ch\/wp-content\/uploads\/2013\/10\/redebeitrage_interventions_1.pdf\"  target=\"_self\" class=\"button-link button-link-default\" >Dossier des m\u00e9dias<span class=\"button-media-date\">13.05.2026<\/span><\/a><\/div><\/div><div class=\"button-list-item\"><div class=\"button-wrapper \"><a href=\"http:\/\/stop-gripen.ch\/fr\/\"  target=\"_self\" class=\"button-link button-link-default\" >http:\/\/stop-gripen.ch<span class=\"button-media-date\">13.05.2026<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3cae074138 elementor-widget elementor-widget-spps_button_list\" data-id=\"62f3cae074138\" data-element_type=\"widget\" data-widget_type=\"spps_button_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-list-wrapper wrapper-spacing-small  \"><div class=\"button-list-title\"><h3>Weiterf\u00fchrende Links<\/h3><\/div><div class=\"button-list-container\"><div class=\"button-list-items\"><div class=\"button-list-item\"><div class=\"button-wrapper \"><a href=\"http:\/\/stop-gripen.ch\/de\/\"  target=\"_self\" class=\"button-link button-link-default\" >Kampagnenwebsite: www.stop-gripen.ch<span class=\"button-media-date\">13.05.2026<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"cpt-channel":[2747],"class_list":["post-56913","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","cpt-channel-communiques-de-presse"],"_links":{"self":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/56913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/comments?post=56913"}],"version-history":[{"count":1,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/56913\/revisions"}],"predecessor-version":[{"id":69883,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/56913\/revisions\/69883"}],"wp:attachment":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/media?parent=56913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/categories?post=56913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/tags?post=56913"},{"taxonomy":"cpt-channel","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-channel?post=56913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}