{"id":57019,"date":"2015-01-23T00:00:00","date_gmt":"2015-01-22T23:00:00","guid":{"rendered":"https:\/\/test.sp-ps.ch\/artikel\/rie-3-les-entreprises-doivent-compenser-les-pertes-de-recettes-fiscales\/"},"modified":"2022-08-14T09:52:29","modified_gmt":"2022-08-14T07:52:29","slug":"rie-3-les-entreprises-doivent-compenser-les-pertes-de-recettes-fiscales","status":"publish","type":"post","link":"https:\/\/www.sp-ps.ch\/fr\/artikel\/rie-3-les-entreprises-doivent-compenser-les-pertes-de-recettes-fiscales\/","title":{"rendered":"RIE 3 : les entreprises doivent compenser les pertes de recettes fiscales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"57019\" class=\"elementor elementor-57019 elementor-55429\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62f3cb297fc8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62f3cb297fc8d\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62f3cb297fc8f\" data-id=\"62f3cb297fc8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f3cb2975e42 elementor-widget elementor-widget-text-editor\" data-id=\"62f3cb2975e42\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans la r&eacute;ponse du PS Suisse &agrave; la proc&eacute;dure de consultation, la Pr&eacute;sidence et le Comit&eacute; directeur rappellent ainsi leurs principaux axes sur la r&eacute;forme de l&rsquo;imposition des entreprises 3 (RIE 3) :<ul>\t<li>Suppression des statuts sp&eacute;ciaux cantonaux, tels que l&rsquo;imp&ocirc;t s&eacute;lectif<\/li>\t<li>Compensation int&eacute;grale des pertes de recettes fiscales par les actionnaires et les entreprises<\/li>\t<li>Les <em>licence-boxes <\/em>ou autre construction similaire doivent &ecirc;tre limit&eacute;s au moment de la phase de transition<\/li>\t<li>Plancher de 16% d&rsquo;imposition effective pour l&rsquo;imposition des entreprises<\/li>\t<li>Imposition des gains en capitaux par un calcul unique et sans exception<\/li><\/ul><p>Le PS rappelle &agrave; Eveline Widmer-Schlumpf les exigences qu&rsquo;elle avait elle-m&ecirc;me formul&eacute;es et les trois objectifs partiels qui devaient &ecirc;tre atteints : charge fiscale comp&eacute;titive, acceptation des normes internationales et rendement financier.<\/p><p>Concr&egrave;tement, cela signifie que le souhait des entreprises pour de potentielles baisses fiscales ne doit pas &ecirc;tre le seul but recherch&eacute;. Le r&eacute;sultat de la RIE 3 doit &eacute;galement comprendre l&rsquo;int&eacute;gration des standards internationaux et, avant tout, les pertes de rentr&eacute;es fiscales doivent &ecirc;tre compens&eacute;es &ndash; et ce par les entreprises et les actionnaires, mais en aucun cas par la population.<\/p><p>Le PS ne veut pas revivre une d&eacute;b&acirc;cle financi&egrave;re, comme ce fut le cas avec l&rsquo;ancien conseiller f&eacute;d&eacute;ral Merz lors de la seconde RIE. Une nouvelle escroquerie de ce type doit absolument &ecirc;tre &eacute;vit&eacute;e. Le PS, alarm&eacute; par les mensonges pass&eacute;s et les ruses utilis&eacute;es, restera particuli&egrave;rement attentif &agrave; la RIE 3 et barrera la route de toute r&eacute;forme malheureuse dont la facture devrait &ecirc;tre support&eacute;e par la population.&nbsp;<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3cb297f2b5 elementor-widget elementor-widget-spps_button_list\" data-id=\"62f3cb297f2b5\" data-element_type=\"widget\" data-widget_type=\"spps_button_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-list-wrapper wrapper-spacing-small  \"><div class=\"button-list-container\"><div class=\"button-list-items\"><div class=\"button-list-item\"><div class=\"button-wrapper \"><a href=\"https:\/\/www.sp-ps.ch\/wp-content\/uploads\/2015\/01\/vernehmlassungsantwort_usr_iii_definitiv_fr.pdf\"  target=\"_self\" class=\"button-link button-link-default\" >R\u00e9ponse du PS Suisse \u00e0 la proc\u00e9dure de consultation sur la RIE 3<span class=\"button-media-date\">13.05.2026<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le PS ne soutiendra la r\u00e9forme de l\u2019imposition des entreprises III (RIE 3) qu\u2019\u00e0 la seule condition que les entreprises et les actionnaires compensent int\u00e9gralement les pertes de recettes fiscales. Marina Carobbio, vice-pr\u00e9sidente du PS Suisse, pr\u00e9cise que \u00ab le PS ne pourra tol\u00e9rer que la population doive payer une baisse fiscale pour les entreprises \u00bb. La Suisse doit adopter les prescriptions internationales en mati\u00e8re d\u2019imposition des entreprises et supprimer les statuts sp\u00e9ciaux dans les cantons. Il est hors de question de risquer de nouvelles pertes se chiffrant en milliards ou de cr\u00e9er de nouvelles niches fiscales. Enfin, le PS n\u2019acceptera pas non plus que les partis de droite utilisent le pr\u00e9texte de l\u2019abolition du cours plancher pour entamer une d\u00e9r\u00e9gulation.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"cpt-channel":[2747],"class_list":["post-57019","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","cpt-channel-communiques-de-presse"],"_links":{"self":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/comments?post=57019"}],"version-history":[{"count":1,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57019\/revisions"}],"predecessor-version":[{"id":69988,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57019\/revisions\/69988"}],"wp:attachment":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/media?parent=57019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/categories?post=57019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/tags?post=57019"},{"taxonomy":"cpt-channel","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-channel?post=57019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}