{"id":57333,"date":"2016-06-25T00:00:00","date_gmt":"2016-06-24T22:00:00","guid":{"rendered":"https:\/\/test.sp-ps.ch\/artikel\/les-delegue-e-s-confirment-le-referendum-face-a-la-demesure-de-la-rie-iii\/"},"modified":"2022-08-14T09:56:36","modified_gmt":"2022-08-14T07:56:36","slug":"les-delegue-e-s-confirment-le-referendum-face-a-la-demesure-de-la-rie-iii","status":"publish","type":"post","link":"https:\/\/www.sp-ps.ch\/fr\/artikel\/les-delegue-e-s-confirment-le-referendum-face-a-la-demesure-de-la-rie-iii\/","title":{"rendered":"Les d\u00e9l\u00e9gu\u00e9-e-s confirment le r\u00e9f\u00e9rendum face \u00e0 la d\u00e9mesure de la RIE III"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"57333\" class=\"elementor elementor-57333 elementor-55683\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62f3cbf1b8919 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62f3cbf1b8919\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62f3cbf1b891c\" data-id=\"62f3cbf1b891c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f3cbf18e91d elementor-widget elementor-widget-text-editor\" data-id=\"62f3cbf18e91d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avec la RIE III, la majorit&eacute; de droite a d&eacute;cid&eacute; de nombreux nouveaux privil&egrave;ges et &eacute;chappatoires pour les riches actionnaires et les grosses entreprises. Cela creusera un trou de 1,3 milliard de francs pour les seules caisses de la Conf&eacute;d&eacute;ration, auxquels s&rsquo;ajouteront d&rsquo;autres milliards de pertes dans les cantons, les villes et les communes. La facture sera directement adress&eacute;e aux contribuables avec, &agrave; la clef, des hausses d&rsquo;imp&ocirc;ts et des coupes dans les prestations.<p>La RIE III est symptomatique du bilan de la l&eacute;gislature actuelle. &laquo; La majorit&eacute; de droite impose son pouvoir, et cela dans presque tous les domaines &raquo;, expliquait Christian Levrat dans son discours. &laquo; Cela nous oblige &agrave; mener une politique d&rsquo;opposition active, d&eacute;termin&eacute;e et efficace &raquo;.<\/p><p>Le PS est d&eacute;cid&eacute; &agrave; d&eacute;fendre les int&eacute;r&ecirc;ts de la population aux urnes &ndash; la RIE III n&rsquo;est qu&rsquo;un d&eacute;but. &laquo; En tant que PS nous devons donner une voix &agrave; toute personne dont les int&eacute;r&ecirc;ts ne correspondent pas &agrave; ceux du PDC, du PLR et de l&rsquo;UDC &raquo;, ces mots sont ceux de la r&eacute;solution adopt&eacute;e samedi. Alors m&ecirc;me que la majorit&eacute; de droite s&rsquo;est prononc&eacute;e, &laquo; les gens n&rsquo;ont pas vot&eacute; pour des attaques contre le budget public et les assurances sociales &raquo;.<\/p><p>Le conseiller f&eacute;d&eacute;ral Alain Berset a quant &agrave; lui fait r&eacute;f&eacute;rence au Brexit. Le Brexit est un &laquo; coup dur politique &raquo; pour l&rsquo;Europe et pour la Suisse qui est contrainte d&rsquo;agir. Ainsi, les abus sur le march&eacute; du travail doivent &ecirc;tre combattus. &laquo; Le dumping salarial sape le fondement d&rsquo;une Suisse ouverte sur le monde &raquo;. De plus, les conditions sociales de notre population doivent globalement &ecirc;tre am&eacute;lior&eacute;es. Enfin, la r&eacute;forme de la pr&eacute;voyance vieillesse doit &ecirc;tre men&eacute;e &agrave; son terme. Et elle ne r&eacute;ussira que si la hausse des rentes et un &acirc;ge de la retraite &agrave; 65 peuvent &ecirc;tre pr&eacute;serv&eacute;s.<\/p><p>Enfin, les d&eacute;l&eacute;gu&eacute;-e-s du PS Suisse se sont prononc&eacute;s sur les objets soumis &agrave; votation le 25 septembre prochaine. L&rsquo;initiative AVSplus, qui pr&eacute;voit enfin une hausse significative des rentes, a &eacute;t&eacute; soutenue unanimement par 131 voix. L&rsquo;initiative &laquo; &eacute;conomie verte &raquo; par 133 voix et une abstention. Au sujet de la loi sur le renseignement (LRens), les d&eacute;l&eacute;gu&eacute;-e-s recommandent le NON par 125 voix, contre 15 et 7 abstentions.<\/p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3cbf1b7ad4 elementor-widget elementor-widget-spps_button_list\" data-id=\"62f3cbf1b7ad4\" data-element_type=\"widget\" data-widget_type=\"spps_button_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-list-wrapper wrapper-spacing-small  \"><div class=\"button-list-container\"><div class=\"button-list-items\"><div class=\"button-list-item\"><div class=\"button-wrapper \"><a href=\"http:\/\/www.sp-ps.ch\/sites\/default\/files\/documents\/160625_rede_levrat_final.pdf\"  target=\"_self\" class=\"button-link button-link-default\" >Discours de Christian Levrat<span class=\"button-media-date\">13.05.2026<\/span><\/a><\/div><\/div><div class=\"button-list-item\"><div class=\"button-wrapper \"><a href=\"http:\/\/www.sp-ps.ch\/sites\/default\/files\/documents\/aufruf_f.pdf\"  target=\"_self\" class=\"button-link button-link-default\" >R\u00e9solution Appel \u00e0 une politique d'opposition constructive<span class=\"button-media-date\">13.05.2026<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le PS est pr\u00eat \u00e0 mener une politique d\u2019opposition active contre le cartel de droite. C\u2019est ce qu\u2019ont confirm\u00e9, dans une r\u00e9solution, les d\u00e9l\u00e9gu\u00e9-e-s du PS Suisse aujourd\u2019hui \u00e0 Coire. Il est question de d\u00e9fendre les int\u00e9r\u00eats de la population contre l\u2019avidit\u00e9 des riches et des puissants, si besoin est au travers des urnes. C\u2019est pourquoi les d\u00e9l\u00e9gu\u00e9-e-s ont vot\u00e9 unanimement le r\u00e9f\u00e9rendum contre la r\u00e9forme d\u00e9mesur\u00e9e et surcharg\u00e9e sur l\u2019imposition des entreprises III (RIE III).<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"cpt-channel":[2747],"class_list":["post-57333","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","cpt-channel-communiques-de-presse"],"_links":{"self":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/comments?post=57333"}],"version-history":[{"count":1,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57333\/revisions"}],"predecessor-version":[{"id":70239,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57333\/revisions\/70239"}],"wp:attachment":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/media?parent=57333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/categories?post=57333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/tags?post=57333"},{"taxonomy":"cpt-channel","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-channel?post=57333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}