{"id":57928,"date":"2019-11-20T00:00:00","date_gmt":"2019-11-19T23:00:00","guid":{"rendered":"https:\/\/test.sp-ps.ch\/artikel\/proteger-lespace-aerien-et-les-interets-des-contribuables\/"},"modified":"2022-08-14T10:04:48","modified_gmt":"2022-08-14T08:04:48","slug":"proteger-lespace-aerien-et-les-interets-des-contribuables","status":"publish","type":"post","link":"https:\/\/www.sp-ps.ch\/fr\/artikel\/proteger-lespace-aerien-et-les-interets-des-contribuables\/","title":{"rendered":"Prot\u00e9ger l\u2019espace a\u00e9rien et les int\u00e9r\u00eats des contribuables"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"57928\" class=\"elementor elementor-57928\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62f3cd5589e53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62f3cd5589e53\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62f3cd5589e56\" data-id=\"62f3cd5589e56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f3cd55852b1 elementor-widget elementor-widget-text-editor\" data-id=\"62f3cd55852b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><p>Sous la pression des partis bourgeois, le DDPS souhaite doter la flotte a&eacute;rienne suisse d&rsquo;avions de combat surdimensionn&eacute;s et luxueux. Cependant, l&rsquo;acquisition de tels avions repr&eacute;sente des co&ucirc;ts exorbitants, surtout consid&eacute;rant leur emploi sporadique. En effet, la formation des pilotes et la r&eacute;alit&eacute; quotidienne des missions de police a&eacute;rienne en Suisse ne requi&egrave;rent l&rsquo;utilisation d&rsquo;avions de combat ultraperformants que dans une minorit&eacute; de situations. L&rsquo;achat d&rsquo;un mod&egrave;le d&rsquo;avion de combat l&eacute;ger, tel que le Leonardo M-346 FA, co&ucirc;terait en revanche quatre fois moins cher et mener des missions de police a&eacute;rienne avec cet appareil repr&eacute;senteraient des co&ucirc;ts six fois moins &eacute;lev&eacute;s. Ce choix de mod&egrave;le permettrait, de plus, de prolonger consid&eacute;rablement la dur&eacute;e de vie des actuels F\/A-18 Hornet, r&eacute;serv&eacute;s pour des missions de protection plus complexes.&nbsp;<\/p><p>&nbsp;<\/p><p>L&#8217;&eacute;tude sur la protection de l&rsquo;espace a&eacute;rien &laquo;&thinsp;Air2030plus&thinsp;&raquo;, telle qu&rsquo;&eacute;labor&eacute;e par ACAMAR sur demande du PS, part du constat que les plans suisses de d&eacute;fense a&eacute;rienne ne sont pas en ad&eacute;quation avec la r&eacute;alit&eacute; des champs de bataille futurs. D&egrave;s lors, &laquo;&thinsp;Air2030plus&thinsp;&raquo; sugg&egrave;re l&rsquo;am&eacute;lioration des dispositifs radars, du syst&egrave;me de conduite et contr&ocirc;le des op&eacute;rations et de la d&eacute;fense sol-air afin de garantir la meilleure s&eacute;curit&eacute; du ciel suisse. Pour Pierre-Alain Fridez, conseiller national (JU), &laquo;&thinsp;ces mesures, coupl&eacute;es &agrave; l&rsquo;utilisation d&rsquo;un avion de combat l&eacute;ger, permettraient d&rsquo;&eacute;conomiser la moiti&eacute; du budget pr&eacute;vu pour le projet du DDPS, tout en limitant la pollution atmosph&eacute;rique et sonore&thinsp;&raquo;. Une double s&eacute;curit&eacute; &agrave; moiti&eacute; prix prot&egrave;ge ainsi l&rsquo;espace a&eacute;rien suisse, mais &eacute;galement les int&eacute;r&ecirc;ts des contribuables. Le PS demande donc au Conseil f&eacute;d&eacute;ral de revoir son projet de d&eacute;fense, faute de quoi un r&eacute;f&eacute;rendum sera envisag&eacute;.<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3cd55852ca elementor-widget elementor-widget-spps_button_list\" data-id=\"62f3cd55852ca\" data-element_type=\"widget\" data-widget_type=\"spps_button_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"button-list-wrapper wrapper-spacing-small  \"><div class=\"button-list-title\"><h3>Dossier complet 'AIR2030plus'<\/h3><\/div><div class=\"button-list-container\"><div class=\"button-list-items\"><div class=\"button-list-item\"><div class=\"button-wrapper \"><a href=\"https:\/\/www.sp-ps.ch\/fr\/dossiers\/paix-et-securite\/protection-de-lespace-aerien-suisse\"  target=\"_self\" class=\"button-link button-link-default\" >Documentation<span class=\"button-media-date\">13.05.2026<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La d\u00e9cision d\u2019acheter de nouveaux avions de combat a de grandes implications politiques et financi\u00e8res pour la population suisse. Se basant sur l\u2019\u00e9tude du groupe de r\u00e9flexion am\u00e9ricain ACAMAR et des auditions publiques de diff\u00e9rents experts, le PS Suisse insiste sur une alternative plus r\u00e9aliste et moins on\u00e9reuse au projet de d\u00e9fense de l\u2019espace a\u00e9rien du D\u00e9partement f\u00e9d\u00e9ral de la d\u00e9fense (DDPS)\u2009: prolonger la dur\u00e9e de vie des F\/A-18 Hornet, tout en r\u00e9alisant d\u2019importantes \u00e9conomies gr\u00e2ce \u00e0 l\u2019acquisition d\u2019un mod\u00e8le d\u2019avion de combat l\u00e9ger et \u00e0 des mesures d\u2019am\u00e9lioration de la s\u00e9curit\u00e9 a\u00e9rienne.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"cpt-channel":[2747],"class_list":["post-57928","post","type-post","status-publish","format-standard","hentry","category-non-classifiee","cpt-channel-communiques-de-presse"],"_links":{"self":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/comments?post=57928"}],"version-history":[{"count":1,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57928\/revisions"}],"predecessor-version":[{"id":70711,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/posts\/57928\/revisions\/70711"}],"wp:attachment":[{"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/media?parent=57928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/categories?post=57928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/tags?post=57928"},{"taxonomy":"cpt-channel","embeddable":true,"href":"https:\/\/www.sp-ps.ch\/fr\/wp-json\/wp\/v2\/cpt-channel?post=57928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}